{"id":5,"date":"2020-01-08T20:54:55","date_gmt":"2020-01-08T20:54:55","guid":{"rendered":"https:\/\/medionik-chur.ch\/wp1\/?page_id=5"},"modified":"2020-01-27T16:20:20","modified_gmt":"2020-01-27T16:20:20","slug":"team","status":"publish","type":"page","link":"https:\/\/medionik-chur.ch\/wp1\/team\/","title":{"rendered":"Team"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"452\" src=\"https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-1024x452.jpg\" alt=\"\" class=\"wp-image-6\" srcset=\"https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-1024x452.jpg 1024w, https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-300x132.jpg 300w, https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-768x339.jpg 768w, https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-1536x678.jpg 1536w, https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-2048x904.jpg 2048w, https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-1200x530.jpg 1200w, https:\/\/medionik-chur.ch\/wp1\/wp-content\/uploads\/2020\/01\/portrait-beide-1980x874.jpg 1980w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption>Walter und Therese Bolliger<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Walter\u00a0Bolliger<\/strong><br>Dipl. Elektro-Ingenieur HTL<\/h3>\n\n\n\n<p>Als Elektroingenieur habe ich mich in meinem Beruf vorwiegend mit Bergbahnen und touristischen Infrastrukturanlagen besch\u00e4ftigt. Daneben interessierten mich schon immer weitere, nicht genau erkl\u00e4rbare Zusammenh\u00e4nge wie Einfluss von Biorhythmus und Bioresonanz auf Menschen, Tiere und Planzen. Dadurch lernte ich das faszinierende Radionik \/ Medionik &#8211; System kennen.&nbsp;Ich habe Seminare und Kurse besucht und im Herbst&nbsp; 2008 von der Radionik Academy Deutschland, das Zertifikat Medionik Coach (CMC) erhalten. <\/p>\n\n\n\n<p>Erg\u00e4nzend zur Medionik-Coach-Ausbildung habe ich&nbsp;mich&nbsp;zum Elektrosmog- Messtechniker (Niederfrequenz und Hochfrequenz)&nbsp;weitergebildet. In neuester Zeit habe ich diverse Kurse und Seminare im Bereich Bioresonanz, Quantenphysik und Metaphysik besucht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Therese Bolliger<\/strong><br>Dipl. Logop\u00e4din und Audioagogin\u00a0\u00a0<\/h3>\n\n\n\n<p>W\u00e4hrend meiner beruflichen T\u00e4tigkeit befasste ich mich haupts\u00e4chlich mit Sprache und Geh\u00f6r. Diese beiden Gebiete lehrten mich achtsam mit Menschen umzugehen, die sich im Alltag oder bei besonderen Ereignissen mit kleinen und grossen Einschr\u00e4nkungen oder Problemen&nbsp; zurecht finden m\u00fcssen. Den einen gelingt dies m\u00fchelos, andere nehmen gerne auch unkonventionelle Unterst\u00fctzung und Beratung in Anspruch. Mit der Medionik-Coach-Ausbildung   hat dieses Angebot eine interessante und erfolgversprechende Erweiterung erfahren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Walter\u00a0BolligerDipl. Elektro-Ingenieur HTL Als Elektroingenieur habe ich mich in meinem Beruf vorwiegend mit Bergbahnen und touristischen Infrastrukturanlagen besch\u00e4ftigt. Daneben interessierten mich schon immer weitere, nicht genau erkl\u00e4rbare Zusammenh\u00e4nge wie Einfluss von Biorhythmus und Bioresonanz auf Menschen, Tiere und Planzen. Dadurch lernte ich das faszinierende Radionik \/ Medionik &#8211; System kennen.&nbsp;Ich habe Seminare und Kurse besucht &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/medionik-chur.ch\/wp1\/team\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eTeam\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/pages\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":8,"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/pages\/5\/revisions"}],"predecessor-version":[{"id":67,"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/pages\/5\/revisions\/67"}],"wp:attachment":[{"href":"https:\/\/medionik-chur.ch\/wp1\/wp-json\/wp\/v2\/media?parent=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}